{"id":19721,"date":"2025-12-23T15:46:07","date_gmt":"2025-12-23T15:46:07","guid":{"rendered":"https:\/\/federacioncanariadehipica.es\/inicio\/?post_type=tribe_events&#038;p=19721"},"modified":"2026-07-15T11:05:14","modified_gmt":"2026-07-15T10:05:14","slug":"la-palma-ecuestre-carreras-tradicionales-en-asfalto-18","status":"publish","type":"tribe_events","link":"https:\/\/federacioncanariadehipica.es\/inicio\/evento\/la-palma-ecuestre-carreras-tradicionales-en-asfalto-18\/","title":{"rendered":"La Palma Ecuestre | Carreras tradicionales en asfalto"},"content":{"rendered":"<h2 class=\"p1\">\u00a1Le damos la bienvenidos a los amantes de la h\u00edpica!<\/h2>\n<p class=\"p1\">Les presentamos un evento imprescindible de esta emocionante disciplina. Se llevar\u00e1 a cabo en <b>La Palma\u00a0<\/b> y se tratar\u00e1 de una competici\u00f3n de <b>Carreras Tradicionales en asfalto<\/b>.<\/p>\n<p class=\"p1\">Los competidores que participar\u00e1n en este evento son algunos de los m\u00e1s destacados en su campo y prometen ofrecer un espect\u00e1culo de primer nivel. Con su habilidad y destreza, los deportistas y sus equinos dejar\u00e1n al p\u00fablico sin aliento mientras compiten por el primer lugar.<\/p>\n<p class=\"p1\">No importa si eres un experto en la disciplina o si esta es tu primera vez asistiendo a un evento de h\u00edpica, esta competici\u00f3n ser\u00e1 una experiencia inolvidable para todos. Disfruta de la emoci\u00f3n de la competici\u00f3n mientras apoyas a tus deportistas favoritos y observas su habilidad en acci\u00f3n.<\/p>\n<p class=\"p1\">Adem\u00e1s, disfruta del ambiente \u00fanico que se crea en los eventos de h\u00edpica, con el sonido de los cascos de los caballos y la emoci\u00f3n palpable en el aire. Podr\u00e1s disfrutar de una jornada divertida y apasionante, rodeado de otros aficionados a la h\u00edpica.<\/p>\n<p class=\"p1\">As\u00ed que no pierdas la oportunidad de ver a los deportistas y sus caballos en acci\u00f3n en este evento de h\u00edpica. Aseg\u00farate de marcar la fecha en tu calendario y nos vemos en el evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Le damos la bienvenidos a los amantes de la h\u00edpica! Les presentamos un evento imprescindible de esta emocionante disciplina. Se llevar\u00e1 a cabo en La Palma\u00a0 y se tratar\u00e1 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":282,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[6],"class_list":["post-19721","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-carreras","cat_carreras"],"acf":{"avance_de_programa":"","avance_de_programa_territorial":"","avance_de_programa_nacional":"","avance_de_programa_paralimpica":"","avance_de_programa_FEI":"","programa":"","inscripciones":"","inscripciones_territorial":"","inscripciones_nacional":"","inscripciones_paralimpica":"","inscripciones_cei1e":"","inscripciones_cei2e":"","inscripciones_ceiyj1e":"","inscripciones_ceiyj2e":"","inscripciones_cen2e":"","inscripciones_cen1e":"","inscripciones_cenyj1e":"","inscripciones_cena0e":"","inscripciones_cea_p60":"","inscripciones_cea_p40":"","inscripciones_cea_i20":"","inscripciones_correo":"","inscritos":"","inscritos_territoriales":"","inscritos_nacionales":"","inscritos_paralimpica":"","inscritos_cei2e":"","inscritos_cei1e":"","inscritos_ceiyj1e":"","inscritos_ceiyj2e":"","inscritos_cen2e":"","inscritos_cen1e":"","inscritos_cenyj1e":"","inscritos_cea0e":"","inscritos_cea_p60":"","inscritos_cea_p40":"","inscritos_cea_i20":"","lista_de_admitidos":"","resultados":"","orden_de_salida":"","fecha_inicio_inscripciones":"20260706","fecha_inscripciones":"20260715","aviso_importante":"","clave_evento":""},"_links":{"self":[{"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tribe_events\/19721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tribe_events\/19721\/revisions"}],"predecessor-version":[{"id":19723,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tribe_events\/19721\/revisions\/19723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/media?parent=19721"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tags?post=19721"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/federacioncanariadehipica.es\/inicio\/wp-json\/wp\/v2\/tribe_events_cat?post=19721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}